{"id":122,"count":0,"description":"","link":"https:\/\/holelisting.com\/de\/nepal\/","name":"Nepal","slug":"nepal","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/holelisting.com\/de\/wp-json\/wp\/v2\/categories\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holelisting.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/holelisting.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/holelisting.com\/de\/wp-json\/wp\/v2\/place?categories=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}