{"id":47,"date":"2022-08-04T08:55:16","date_gmt":"2022-08-04T08:55:16","guid":{"rendered":"https:\/\/holelisting.com\/?page_id=47"},"modified":"2022-09-03T13:32:57","modified_gmt":"2022-09-03T13:32:57","slug":"glory-hole","status":"publish","type":"page","link":"https:\/\/holelisting.com\/pt\/glory-hole\/","title":{"rendered":"Adicione sua localiza\u00e7\u00e3o"},"content":{"rendered":"<section class=\"glory-hole-location\">\n<h1>Adicione sua localiza\u00e7\u00e3o<\/h1>\n<p class=\"text-center\" style=\"margin-top:-20px\">Voc\u00ea deve estar conectado para adicionar um local<\/p>\n<div class=\"glory-authorization-form\">\n\n<div class=\"login-form\">\n  \n<div class=\"login-form-wrap\">\n\n\n\n\n<h2>Conecte-se<\/h2>\n\n\n\n\t\t<form class=\"wpv-form\" name=\"loginform\" id=\"loginform\" action=\"https:\/\/holelisting.com\/wp-login.php\" method=\"post\">\n\t\t\t<div class=\"wp-success\"><\/div>\n\t\t\t<p class=\"login-username\">\n\t\t\t\t<label for=\"user_login\">Username or Email<\/label>\n\t\t\t\t<input type=\"text\" name=\"log\" id=\"user_login\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p>\n\t\t\t<p class=\"login-password\">\n\t\t\t\t<label for=\"user_pass\">Senha<\/label>\n\t\t\t\t<input type=\"password\" name=\"pwd\" id=\"user_pass\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p>\n\t\t\t\n\t\t\t\n\t\t\t<p class=\"login-submit\">\n\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wp-submit\" class=\"button-primary\" value=\"Iniciar sess\u00e3o\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/pages\/47\" \/>\n\t\t\t<\/p>\n\t\t\t<input type=\"hidden\" name=\"wpv_login_form\" value=\"on\"\/>\n\t\t<\/form>\n<\/div>\n  \n\n\n\n\n\n\n\n\n\n<div class=\"login-form-link forgot-link\">Esqueceu sua senha?<\/div>\n<div class=\"forgot-form none\"><h2>Recupera\u00e7\u00e3o de senha<\/h2>\n\t\t<form class=\"wpv-form\" name=\"forgotpasswordform\" id=\"forgotpasswordform\" action=\"https:\/\/holelisting.com\/wp-login.php?action=lostpassword\" method=\"post\">\n\t\t\t<div class=\"wp-success\"><\/div>\n\t\t\t<p class=\"login-username\">\n\t\t\t\t<label for=\"user_login\">Username or Email<\/label>\n\t\t\t\t<input type=\"text\" name=\"user_login\" id=\"user_login\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p>\n\t\t\t\n\t\t\t<p class=\"login-submit\">\n\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wp-submit\" class=\"button-primary\" value=\"Get New Password\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"\" \/>\n\t\t\t<\/p>\n\t\t\t<input type=\"hidden\" name=\"wpv_forgot_password_form\" value=\"on\"\/><input type=\"hidden\" name=\"wpv_forgot_password_form_redirect_on_fail\" value=\"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/pages\/47\" \/>\n\t\t<\/form><\/div>\n<div class=\"login-form-link register-link\">N\u00e3o \u00e9 um membro? <span>Inscrever-se<\/span><\/div>\n\n  \n\n  \n\n\n  \n<\/div>\n  \n\n<div class=\"register-form none\">\n\n\n\n\n<h2>Registro<\/h2>\n\n\n<form  id=\"cred_user_form_71_1_1\" class=\"cred-user-form cred-keep-original\" action=\"\/pt\/wp-json\/wp\/v2\/pages\/47?_tt=1784091333\" data-form=\"{&quot;form_id&quot;:&quot;cred_user_form_71_1_1&quot;,&quot;use_ajax&quot;:&quot;1&quot;,&quot;wpv_page&quot;:1}\" data-conditionals=\"[]\" method=\"post\">\r\n<div id=\"wpt-form-message-71\"\n\t\t\t              data-message-single=\"\"\n\t\t\t              data-message-plural=\"\"\n\t\t\t              style=\"display:none;\" class=\"wpt-top-form-error wpt-form-error wpt-form-error-wrapper alert alert-danger alert alert-warning\"><\/div>\r\n\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"email-user_email\">\r\n<input type=\"text\" id=\"cred_user_form_71_1_1_user_email\" name=\"user_email\" value=\"\" preset_value=\"\" urlparam=\"\" make_readonly=\"\" max_width=\"\" max_height=\"\" class=\"form-control email-input wpt-form-textfield form-textfield textfield\" output=\"bootstrap\" placeholder=\"\" data-wpt-validate=\"{&quot;email&quot;:{&quot;args&quot;:{&quot;1&quot;:true},&quot;message&quot;:&quot;Please enter a valid email address&quot;},&quot;required&quot;:{&quot;args&quot;:{&quot;1&quot;:true},&quot;message&quot;:&quot;This field is required&quot;}}\" data-wpt-field-title=\"Email\" data-parsley-type=\"email\" data-parsley-error-message=\"Please enter a valid email address\" data-parsley-required=\"true\" data-parsley-required-message=\"This field is required\" data-parsley-credfilesize=\"2097152\" data-wpt-type=\"textfield\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_user_email\" data-wpt-name=\"user_email\" \/>\r\n<\/div>\r\n<div class=\"glory-two-col\">\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"textfield-first_name\">\r\n<input type=\"text\" id=\"cred_user_form_71_1_1_first_name\" name=\"first_name\" value=\"\" class=\"form-control first-name-input wpt-form-textfield form-textfield textfield\" output=\"bootstrap\" preset_value=\"\" urlparam=\"\" preview=\"\" previewsize=\"\" select_label=\"\" edit_label=\"\" value_escape=\"\" make_readonly=\"\" placeholder=\"\" select_text=\"\" data-wpt-type=\"textfield\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_first_name\" data-wpt-name=\"first_name\" \/>\r\n<\/div>\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"textfield-last_name\">\r\n<input type=\"text\" id=\"cred_user_form_71_1_1_last_name\" name=\"last_name\" value=\"\" class=\"form-control last-name-input wpt-form-textfield form-textfield textfield\" output=\"bootstrap\" preset_value=\"\" urlparam=\"\" preview=\"\" previewsize=\"\" select_label=\"\" edit_label=\"\" value_escape=\"\" make_readonly=\"\" placeholder=\"\" select_text=\"\" data-wpt-type=\"textfield\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_last_name\" data-wpt-name=\"last_name\" \/>\r\n<\/div>\r\n<\/div>\r\n<div class=\"glory-two-col\">\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"password-user_pass\">\r\n<input type=\"password\" id=\"cred_user_form_71_1_1_user_pass\" name=\"user_pass\" value=\"\" preset_value=\"\" urlparam=\"\" make_readonly=\"\" max_width=\"\" max_height=\"\" class=\"form-control password-input wpt-form-password form-password password\" output=\"bootstrap\" placeholder=\"\" data-wpt-validate=\"{&quot;required&quot;:{&quot;args&quot;:{&quot;1&quot;:true},&quot;message&quot;:&quot;This field is required&quot;}}\" data-wpt-field-title=\"Password\" data-parsley-required=\"true\" data-parsley-required-message=\"This field is required\" data-parsley-credfilesize=\"2097152\" data-wpt-type=\"password\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_user_pass\" data-wpt-name=\"user_pass\" \/>\r\n<\/div>\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"password-user_pass2\">\r\n<input type=\"password\" id=\"cred_user_form_71_1_1_user_pass2\" name=\"user_pass2\" value=\"\" preset_value=\"\" urlparam=\"\" make_readonly=\"\" max_width=\"\" max_height=\"\" class=\"form-control password-input-repeat wpt-form-password form-password password\" output=\"bootstrap\" placeholder=\"\" data-wpt-validate=\"{&quot;equalto&quot;:{&quot;args&quot;:{&quot;1&quot;:&quot;user_pass&quot;},&quot;message&quot;:&quot;Passwords do not match&quot;}}\" data-wpt-field-title=\"Repeat Password\" data-wpt-type=\"password\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_user_pass2\" data-wpt-name=\"user_pass2\" \/>\r\n<\/div>\r\n<\/div>\r\n\r\n<div class=\"register-form-privacy\">\r\n<div class=\"js-wpt-field-items js-wpt-repetitive wpt-repetitive\" data-initial-conditional=\"\" data-item_name=\"checkbox-user-acceptance\"><input type=\"checkbox\" id=\"cred_user_form_71_1_1_user-acceptance\" name=\"user-acceptance\" data-wpt-type=\"checkbox\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1_user-acceptance\" data-wpt-name=\"user-acceptance\" value=\"1\" class=\" wpt-form-checkbox form-checkbox checkbox\" preset_value=\"\" cred_generic=\"1\" placeholder=\"\" preview=\"\" previewsize=\"\" urlparam=\"\" data-wpt-validate=\"{&quot;required&quot;:{&quot;args&quot;:{&quot;1&quot;:true},&quot;message&quot;:&quot;This field is required&quot;}}\" data-wpt-field-title=\"Eu aceito a pol\u00edtica de privacidade\" data-parsley-required=\"true\" data-parsley-required-message=\"This field is required\" data-parsley-credfilesize=\"2097152\" \/>&nbsp;<label class=\"wpt-form-label wpt-form-checkbox-label\" for=\"cred_user_form_71_1_1_user-acceptance\">Eu aceito a pol\u00edtica de privacidade&#42;<\/label>\r\n<input type=\"hidden\" name=\"_wptoolset_checkbox[cred_user_form_71_1_1_user-acceptance]\" value=\"1\" \/>\r\n\r\n<\/div>\r\n<p>Ler <a href=\"https:\/\/holelisting.com\/pt\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de Privacidade<\/a><\/p>\r\n<\/div>\r\n\r\n<input type=\"submit\" id=\"cred_user_form_71_1_1_form_submit_1\" name=\"form_submit_1\" value=\"Registro\" class=\"btn btn-primary btn-lg wpt-form-submit form-submit submit\" \/>\r\n<input type=\"hidden\" id=\"cred_user_form_71_1_1__cred_cred_prefix_cred_container_id\" name=\"_cred_cred_prefix_cred_container_id\" value=\"47\" class=\"wpt-form-hidden form-hidden\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1__cred_cred_prefix_cred_container_id\" data-wpt-name=\"_cred_cred_prefix_cred_container_id\" \/><input type=\"hidden\" id=\"cred_user_form_71_1_1__cred_cred_prefix_form_id\" name=\"_cred_cred_prefix_form_id\" value=\"71\" class=\"wpt-form-hidden form-hidden\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1__cred_cred_prefix_form_id\" data-wpt-name=\"_cred_cred_prefix_form_id\" \/><input type=\"hidden\" id=\"cred_user_form_71_1_1__cred_cred_prefix_form_count\" name=\"_cred_cred_prefix_form_count\" value=\"1\" class=\"wpt-form-hidden form-hidden\" data-wpt-id=\"cred_user_form_71_1_1_cred_user_form_71_1_1__cred_cred_prefix_form_count\" data-wpt-name=\"_cred_cred_prefix_form_count\" \/><\/form>\n<\/div>\n\n<\/div>\n\n\n\n<script>\njQuery(document).ready(function($){\n  \n$( \"input[name='first_name']\").attr(\"required\",true);\n$( \"input[name='last_name']\").attr(\"required\",true);\n$( \"input[name='user_pass']\").attr(\"required\",true);\n$( \"input[name='user_pass2']\").attr(\"required\",true);\n\n\n\n\n\n\n\n\n\n\n$(\".login-form .login-username input\").attr(\"placeholder\", \"Nome de usu\u00e1rio ou email\");\n$(\".login-form .login-password input\").attr(\"placeholder\", \"Senha\");\n$(\".register-form .password-input\").attr(\"placeholder\", \"Senha\");\n$(\".register-form .password-input-repeat\").attr(\"placeholder\", \"Repita a senha\");\n$(\".register-form .email-input\").attr(\"placeholder\", \"E-mail\");\n$(\".register-form .first-name-input\").attr(\"placeholder\", \"Primeiro nome\");\n$(\".register-form .last-name-input\").attr(\"placeholder\", \"Sobrenome\");\n\n  \n\n  \n \n  \n$(\".forgot-link\").click(function(){\n$('.login-form-wrap,.register-form,.login-form-link').addClass('none');\n$('.forgot-form').fadeTo(500, 1).removeClass('none');\nvar element = document.querySelector(\".glory-authorization-form\");\nelement.scrollIntoView({behavior: \"smooth\" ,inline: \"center\"});\n});\n\n$(\".register-link\").click(function(){\n$('.register-form').fadeTo(500, 1).removeClass('none');;\n$('.login-form,.forgot-form').addClass('none');\nvar element = document.querySelector(\".glory-authorization-form\");\nelement.scrollIntoView({behavior: \"smooth\" ,inline: \"center\"});  \n});\n\n  \n});\n<\/script>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>[\/wpv-conditional]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"2.10.7","language":"pt","enabled_languages":["en","es","de","fr","pt","it","nl"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"nl":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":0,"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"wp:attachment":[{"href":"https:\/\/holelisting.com\/pt\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}